{"id":2572,"date":"2020-02-17T10:20:02","date_gmt":"2020-02-17T10:20:02","guid":{"rendered":"https:\/\/grupogispert.com\/blog\/?p=2572"},"modified":"2020-02-17T11:09:52","modified_gmt":"2020-02-17T11:09:52","slug":"barcelona-tech-spirit-evento-alternativo-tras-la-cancelacion-del-mwc","status":"publish","type":"post","link":"https:\/\/grupogispert.com\/blog\/barcelona-tech-spirit-evento-alternativo-tras-la-cancelacion-del-mwc\/","title":{"rendered":"Barcelona Tech Spirit: evento alternativo tras la cancelaci\u00f3n del MWC"},"content":{"rendered":"<p>[et_pb_section bb_built=&#8221;1&#8243;][et_pb_row][et_pb_column type=&#8221;2_3&#8243;][et_pb_text _builder_version=&#8221;3.13.1&#8243;]<\/p>\n<p>Tras el anuncio de la cancelaci\u00f3n del Mobile World Congress, la comunidad startup de Barcelona ha reaccionado organizando unas jornadas de emprendimiento para los d\u00edas 24, 25 y 26 de febrero, con el fin de aglutinar y aprovechar la presencia de los distintos actores (emprendedores, fondos de inversi\u00f3n, etc.) que ya ten\u00edan previsto visitar Barcelona durante dichas fechas.<\/p>\n<p>El nuevo evento, bautizado bajo el t\u00edtulo <strong>Barcelona Tech Spirit<\/strong>, surge de la iniciativa de la Junta Directiva de Barcelona Tech City, el Ayuntamiento de Barcelona, la Generalitat de Catalunya, Mobile World Capital y otras instituciones de la comunidad startup y agrupar\u00e1 una serie de actividades y conferencias de fomento del emprendimiento.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243;][et_pb_text _builder_version=&#8221;3.13.1&#8243;]<\/p>\n<h4>Para m\u00e1s novedades, recomendamos seguir la cuenta de Twitter de Barcelona Tech City.<\/h4>\n<p>[\/et_pb_text][et_pb_social_media_follow _builder_version=&#8221;3.13.1&#8243; text_orientation=&#8221;center&#8221;][et_pb_social_media_follow_network _builder_version=&#8221;3.13.1&#8243; social_network=&#8221;twitter&#8221; skype_action=&#8221;call&#8221; url=&#8221;https:\/\/twitter.com\/bcntechcity&#8221; background_color=&#8221;#00aced&#8221; use_background_color_gradient=&#8221;off&#8221; background_color_gradient_start=&#8221;#2b87da&#8221; background_color_gradient_end=&#8221;#29c4a9&#8243; background_color_gradient_type=&#8221;linear&#8221; background_color_gradient_direction=&#8221;180deg&#8221; background_color_gradient_direction_radial=&#8221;center&#8221; background_color_gradient_start_position=&#8221;0%&#8221; background_color_gradient_end_position=&#8221;100%&#8221; background_color_gradient_overlays_image=&#8221;off&#8221; parallax=&#8221;off&#8221; parallax_method=&#8221;on&#8221; background_size=&#8221;cover&#8221; background_position=&#8221;center&#8221; background_repeat=&#8221;no-repeat&#8221; background_blend=&#8221;normal&#8221; allow_player_pause=&#8221;off&#8221; background_video_pause_outside_viewport=&#8221;on&#8221; box_shadow_style=&#8221;none&#8221;] Twitter [\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Barcelona Tech Spirit surge trasn la cancelaci\u00f3n del Mobile World Congress y agrupar\u00e1 una serie de actividades y conferencias de fomento del emprendimiento.<\/p>\n","protected":false},"author":3,"featured_media":2578,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_mo_disable_npp":""},"categories":[26],"tags":[],"_links":{"self":[{"href":"https:\/\/grupogispert.com\/blog\/wp-json\/wp\/v2\/posts\/2572"}],"collection":[{"href":"https:\/\/grupogispert.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupogispert.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupogispert.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/grupogispert.com\/blog\/wp-json\/wp\/v2\/comments?post=2572"}],"version-history":[{"count":9,"href":"https:\/\/grupogispert.com\/blog\/wp-json\/wp\/v2\/posts\/2572\/revisions"}],"predecessor-version":[{"id":2585,"href":"https:\/\/grupogispert.com\/blog\/wp-json\/wp\/v2\/posts\/2572\/revisions\/2585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupogispert.com\/blog\/wp-json\/wp\/v2\/media\/2578"}],"wp:attachment":[{"href":"https:\/\/grupogispert.com\/blog\/wp-json\/wp\/v2\/media?parent=2572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupogispert.com\/blog\/wp-json\/wp\/v2\/categories?post=2572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupogispert.com\/blog\/wp-json\/wp\/v2\/tags?post=2572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}